{"id":245,"count":1,"description":"","link":"http:\/\/www.terrebritton.com\/studio1\/tag\/funny\/","name":"funny","slug":"funny","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"http:\/\/www.terrebritton.com\/studio1\/wp-json\/wp\/v2\/tags\/245"}],"collection":[{"href":"http:\/\/www.terrebritton.com\/studio1\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"http:\/\/www.terrebritton.com\/studio1\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"http:\/\/www.terrebritton.com\/studio1\/wp-json\/wp\/v2\/posts?tags=245"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}