{"id":23,"count":19,"description":"","link":"http:\/\/www.terrebritton.com\/studio1\/tag\/apples\/","name":"Apples","slug":"apples","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"http:\/\/www.terrebritton.com\/studio1\/wp-json\/wp\/v2\/tags\/23"}],"collection":[{"href":"http:\/\/www.terrebritton.com\/studio1\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"http:\/\/www.terrebritton.com\/studio1\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"http:\/\/www.terrebritton.com\/studio1\/wp-json\/wp\/v2\/posts?tags=23"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}