{"id":211,"count":3,"description":"","link":"http:\/\/www.terrebritton.com\/studio1\/tag\/video\/","name":"Video","slug":"video","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"http:\/\/www.terrebritton.com\/studio1\/wp-json\/wp\/v2\/tags\/211"}],"collection":[{"href":"http:\/\/www.terrebritton.com\/studio1\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"http:\/\/www.terrebritton.com\/studio1\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"http:\/\/www.terrebritton.com\/studio1\/wp-json\/wp\/v2\/posts?tags=211"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}