{"id":123,"count":1,"description":"","link":"http:\/\/www.terrebritton.com\/studio1\/tag\/kremlin\/","name":"Kremlin","slug":"kremlin","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"http:\/\/www.terrebritton.com\/studio1\/wp-json\/wp\/v2\/tags\/123"}],"collection":[{"href":"http:\/\/www.terrebritton.com\/studio1\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"http:\/\/www.terrebritton.com\/studio1\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"http:\/\/www.terrebritton.com\/studio1\/wp-json\/wp\/v2\/posts?tags=123"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}